

{"id":29152,"date":"2024-09-26T15:08:44","date_gmt":"2024-09-26T13:08:44","guid":{"rendered":"https:\/\/www.viennaartweek.at\/?post_type=program&#038;p=29152"},"modified":"2024-09-26T15:08:44","modified_gmt":"2024-09-26T13:08:44","slug":"best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award","status":"publish","type":"program","link":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/","title":{"rendered":"&#8222;Best of Austria \u2013 Best of Europe&#8220; &#8211; Podium im Rahmen der Ausstellung &#8222;Europas beste Bauten. Mies van der Rohe Award&#8220;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":29153,"menu_order":307,"template":"","programm_day":[431],"wholeyear":[445],"event-category":[230,284],"class_list":["post-29152","program","type-program","status-publish","has-post-thumbnail","hentry","programm_day-431","wholeyear-vienna-art-week-2024","event-category-eintritt-frei","event-category-talks-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Best of Austria \u2013 Best of Europe&quot; - Podium im Rahmen der Ausstellung &quot;Europas beste Bauten. Mies van der Rohe Award&quot; | Vienna Art Week 2026<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Best of Austria \u2013 Best of Europe&quot; - Podium im Rahmen der Ausstellung &quot;Europas beste Bauten. Mies van der Rohe Award&quot; | Vienna Art Week 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/\" \/>\n<meta property=\"og:site_name\" content=\"Vienna Art Week 2026\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VIENNAARTWEEK\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@viennaartweek\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/\",\"url\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/\",\"name\":\"\\\"Best of Austria \u2013 Best of Europe\\\" - Podium im Rahmen der Ausstellung \\\"Europas beste Bauten. Mies van der Rohe Award\\\" | Vienna Art Week 2026\",\"isPartOf\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg\",\"datePublished\":\"2024-09-26T13:08:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage\",\"url\":\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg\",\"contentUrl\":\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg\",\"width\":1772,\"height\":1181,\"caption\":\"Die \u00f6sterreichischen Architekturprojekte \u201eTownhouse Neubaugasse\u201c und \u201eIKEA wien westbahnhof\u201c wurden in die Shortlist des EU Mies Award 2024 gew\u00e4hlt. \u00a9 Fotos: Simone Bossi, Hertha Hurnaus, Christine H\u00e4usler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.viennaartweek.at\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\/\/www.viennaartweek.at\/de\/program\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8222;Best of Austria \u2013 Best of Europe&#8220; &#8211; Podium im Rahmen der Ausstellung &#8222;Europas beste Bauten. Mies van der Rohe Award&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#website\",\"url\":\"https:\/\/www.viennaartweek.at\/de\/\",\"name\":\"Vienna Art Week 2025\",\"description\":\"6-13 NOV 2026\",\"publisher\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.viennaartweek.at\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#organization\",\"name\":\"Vienna Art Week\",\"url\":\"https:\/\/www.viennaartweek.at\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2020\/04\/VAW-logo-01-VAW-BLACK.jpg\",\"contentUrl\":\"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2020\/04\/VAW-logo-01-VAW-BLACK.jpg\",\"width\":709,\"height\":484,\"caption\":\"Vienna Art Week\"},\"image\":{\"@id\":\"https:\/\/www.viennaartweek.at\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/VIENNAARTWEEK\/\",\"https:\/\/x.com\/viennaartweek\",\"https:\/\/www.instagram.com\/viennaartweek\",\"https:\/\/www.youtube.com\/channel\/UCKepCir33JArLzmYqGJGI1Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Best of Austria \u2013 Best of Europe\" - Podium im Rahmen der Ausstellung \"Europas beste Bauten. Mies van der Rohe Award\" | Vienna Art Week 2026","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"\"Best of Austria \u2013 Best of Europe\" - Podium im Rahmen der Ausstellung \"Europas beste Bauten. Mies van der Rohe Award\" | Vienna Art Week 2026","og_url":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/","og_site_name":"Vienna Art Week 2026","article_publisher":"https:\/\/www.facebook.com\/VIENNAARTWEEK\/","og_image":[{"width":1772,"height":1181,"url":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@viennaartweek","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/","url":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/","name":"\"Best of Austria \u2013 Best of Europe\" - Podium im Rahmen der Ausstellung \"Europas beste Bauten. Mies van der Rohe Award\" | Vienna Art Week 2026","isPartOf":{"@id":"https:\/\/www.viennaartweek.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage"},"image":{"@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg","datePublished":"2024-09-26T13:08:44+00:00","breadcrumb":{"@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#primaryimage","url":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg","contentUrl":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2024\/07\/AT15\u00a9hertha-hurnaus-haeusler-christine_1-Kopie.jpeg","width":1772,"height":1181,"caption":"Die \u00f6sterreichischen Architekturprojekte \u201eTownhouse Neubaugasse\u201c und \u201eIKEA wien westbahnhof\u201c wurden in die Shortlist des EU Mies Award 2024 gew\u00e4hlt. \u00a9 Fotos: Simone Bossi, Hertha Hurnaus, Christine H\u00e4usler"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viennaartweek.at\/de\/program\/best-of-austria-best-of-europe-podium-im-rahmen-der-ausstellung-europas-beste-bauten-mies-van-der-rohe-award\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.viennaartweek.at\/de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/www.viennaartweek.at\/de\/program\/"},{"@type":"ListItem","position":3,"name":"&#8222;Best of Austria \u2013 Best of Europe&#8220; &#8211; Podium im Rahmen der Ausstellung &#8222;Europas beste Bauten. Mies van der Rohe Award&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.viennaartweek.at\/de\/#website","url":"https:\/\/www.viennaartweek.at\/de\/","name":"Vienna Art Week 2025","description":"6-13 NOV 2026","publisher":{"@id":"https:\/\/www.viennaartweek.at\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viennaartweek.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.viennaartweek.at\/de\/#organization","name":"Vienna Art Week","url":"https:\/\/www.viennaartweek.at\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viennaartweek.at\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2020\/04\/VAW-logo-01-VAW-BLACK.jpg","contentUrl":"https:\/\/www.viennaartweek.at\/wp-content\/uploads\/2020\/04\/VAW-logo-01-VAW-BLACK.jpg","width":709,"height":484,"caption":"Vienna Art Week"},"image":{"@id":"https:\/\/www.viennaartweek.at\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VIENNAARTWEEK\/","https:\/\/x.com\/viennaartweek","https:\/\/www.instagram.com\/viennaartweek","https:\/\/www.youtube.com\/channel\/UCKepCir33JArLzmYqGJGI1Q"]}]}},"_links":{"self":[{"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/program\/29152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/media\/29153"}],"wp:attachment":[{"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/media?parent=29152"}],"wp:term":[{"taxonomy":"programm_day","embeddable":true,"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/programm_day?post=29152"},{"taxonomy":"wholeyear","embeddable":true,"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/wholeyear?post=29152"},{"taxonomy":"event-category","embeddable":true,"href":"https:\/\/www.viennaartweek.at\/de\/wp-json\/wp\/v2\/event-category?post=29152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}